{"id":19,"count":7,"description":"","link":"https:\/\/sevensavenue.ae\/ar\/category\/lookbook\/","name":"Lookbook","slug":"lookbook","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sevensavenue.ae\/ar\/wp-json\/wp\/v2\/categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevensavenue.ae\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sevensavenue.ae\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sevensavenue.ae\/ar\/wp-json\/wp\/v2\/posts?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}